{"id":495,"date":"2017-06-22T17:02:48","date_gmt":"2017-06-22T15:02:48","guid":{"rendered":"http:\/\/gemeinwohlyoga.de\/?p=495"},"modified":"2017-06-22T17:37:11","modified_gmt":"2017-06-22T15:37:11","slug":"newsletter-juni-2017","status":"publish","type":"post","link":"http:\/\/gemeinwohlyoga.de\/index.php\/2017\/06\/22\/newsletter-juni-2017\/","title":{"rendered":"Newsletter Juni 2017 Tagesseminar: Ganzheitliches Reiten und Yoga"},"content":{"rendered":"<p>Newsletter Juni 2017<\/p>\n<p>Liebe Yoga-Interessierte,<\/p>\n<p>\u201eGemeinwohlYoga\u201c hei\u00dft, das Wohl aller Lebewesen im Auge zu behalten und uns zu jeder Zeit der Verbindung bewusst zu sein. Das schlie\u00dft auch die Beziehung zwischen Mensch und Tier mit ein. Mit meiner Kollegin, der Reitlehrerin Christina Kern, m\u00f6chte ich <b>am 8. Juli <\/b>ein <b>Tagesseminar<\/b> anbieten, das <b>Yoga und <\/b><b>ganzheitliches <\/b><b>Reiten<\/b> miteinander verbindet. In einem harmonischen Reitgef\u00fchl spiegelt sich ein w\u00fcrdevoller und wertsch\u00e4tzender Umgang mit dem Pferd wider. Dar\u00fcber hinaus spiegeln Pferde uns Menschen unsere innere Verfassung. <a href=\"http:\/\/gemeinwohlyoga.de\/wp-content\/uploads\/2017\/06\/Newsletter-Juni-2017-Text-und-Bild-2.pdf\">Newsletter Juni 2017 Text und Bild 2<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Newsletter Juni 2017 Liebe Yoga-Interessierte, \u201eGemeinwohlYoga\u201c hei\u00dft, das Wohl aller Lebewesen im Auge zu behalten und uns zu jeder Zeit der Verbindung bewusst zu sein. Das schlie\u00dft auch die Beziehung zwischen Mensch und Tier mit ein. Mit meiner Kollegin, der Reitlehrerin Christina Kern, m\u00f6chte ich am 8. Juli ein Tagesseminar&hellip; <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13,11],"tags":[],"_links":{"self":[{"href":"http:\/\/gemeinwohlyoga.de\/index.php\/wp-json\/wp\/v2\/posts\/495"}],"collection":[{"href":"http:\/\/gemeinwohlyoga.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/gemeinwohlyoga.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/gemeinwohlyoga.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/gemeinwohlyoga.de\/index.php\/wp-json\/wp\/v2\/comments?post=495"}],"version-history":[{"count":2,"href":"http:\/\/gemeinwohlyoga.de\/index.php\/wp-json\/wp\/v2\/posts\/495\/revisions"}],"predecessor-version":[{"id":501,"href":"http:\/\/gemeinwohlyoga.de\/index.php\/wp-json\/wp\/v2\/posts\/495\/revisions\/501"}],"wp:attachment":[{"href":"http:\/\/gemeinwohlyoga.de\/index.php\/wp-json\/wp\/v2\/media?parent=495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/gemeinwohlyoga.de\/index.php\/wp-json\/wp\/v2\/categories?post=495"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/gemeinwohlyoga.de\/index.php\/wp-json\/wp\/v2\/tags?post=495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}